{"id":4410,"date":"2017-09-11T20:49:33","date_gmt":"2017-09-11T19:49:33","guid":{"rendered":"https:\/\/www.kevinmaschke.com\/?p=4410\/"},"modified":"2025-12-07T15:29:50","modified_gmt":"2025-12-07T15:29:50","slug":"his-dark-materials-trilogie-philip-pullman","status":"publish","type":"post","link":"https:\/\/www.kevinmaschke.com\/de\/his-dark-materials-trilogie-philip-pullman\/","title":{"rendered":"His Dark Materials Trilogie, von Philip Pullman"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Sieht aus also w\u00fcrde ich in letzter zeit nur Trilogien lesen! Und nach den <a href=\"https:\/\/www.kevinmaschke.com\/de\/buecher\/die-koenigs-romane-von-joe-abercrombie\/\">K\u00f6nigs-Romanen<\/a>, der Trajan Trilogie (<a href=\"https:\/\/www.kevinmaschke.com\/libros\/trilogia-del-mar-quebrado-de-joe-abercrombie\/\">nur in Spanisch<\/a>) und der <a href=\"https:\/\/www.kevinmaschke.com\/de\/buecher\/weltraum-odyssee-arthur-c-clarke\/\">Weltraum Odyssee<\/a>, war die <strong>His Dark Materials<\/strong> Trilogie an der Reihe. His Dark Materials ist eine Fantasy-Trilogie von <strong>Philip Pullman<\/strong>&nbsp;die aus den B\u00fcchern <em>Der Goldene Kompass<\/em>, <em>Das Magische Messer<\/em> und <em>Das Bernstein-Teleskop<\/em> besteht, und in der wir ein Waisenm\u00e4dchen namens Lyra durch mehrere Universen folgen &nbsp;in denen <strong>Magie, Theologie und Wissenschaft<\/strong> auf diskrete und zugleich&nbsp;gro\u00dfartige Weise verflochten sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In den Romanen begegnen wir <strong>einer Vielzahl von Charakteren<\/strong>, die sich durch ihre Ideologien, kulturellen und gesellschaftlichen Umgebungen und \u00dcberzeugungen sehr unterscheiden -und wir sehen, wie diese Charaktere sich weiterentwickeln und ver\u00e4ndern, einige mehr als andere. <strong>Wir entdecken Verschw\u00f6rungen, finden Action und l\u00fcften Geheimnisse<\/strong> die uns mehr und mehr begeistern werden, umso weiter wir in der Geschichte vorankommen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Popularit\u00e4t der <em>His Dark Materials<\/em> Trilogie f\u00fchrte dazu das New Line Cinema die Rechte kaufte um die Trilogie auf den gro\u00dfen Bildschirm zu bringen, und die Filmversion des ersten Romans erschien ende 2007 in den Kinos als <em>Der Goldene Kompass<\/em>. Da aber <strong>einige der Ideen in den Romanen als Kritik gegen die Religion verstanden werden k\u00f6nnen<\/strong>, wurden diese immer wieder von verschiedenen Konservativen Christlichen Sektoren (wie zum Beispiel der R\u00f6misch-katholische Kirche) kritisiert. Dies zwang Hollywood am ende die Dreharbeiten zum zweiten und dritten Film abzusagen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Synopse<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"691\" height=\"1024\" src=\"https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151653\/Der-Goldene-Kompass_Philip-Pullman_kevinmaschke.com_-1-691x1024.webp\" alt=\"\" class=\"wp-image-9141\" style=\"width:200px\" srcset=\"https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151653\/Der-Goldene-Kompass_Philip-Pullman_kevinmaschke.com_-1-691x1024.webp 691w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151653\/Der-Goldene-Kompass_Philip-Pullman_kevinmaschke.com_-1-270x400.webp 270w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151653\/Der-Goldene-Kompass_Philip-Pullman_kevinmaschke.com_-1-68x100.webp 68w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151653\/Der-Goldene-Kompass_Philip-Pullman_kevinmaschke.com_-1-1037x1536.webp 1037w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151653\/Der-Goldene-Kompass_Philip-Pullman_kevinmaschke.com_-1-100x148.webp 100w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151653\/Der-Goldene-Kompass_Philip-Pullman_kevinmaschke.com_-1.webp 1080w\" sizes=\"auto, (max-width: 691px) 100vw, 691px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Der Goldene Kompass<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lyra Belaqua erf\u00e4hrt von der Existenz vom Staub<\/strong> durch ihren Onkel und erh\u00e4lt vor ihrer Abreise ein Artefakt namens Alethiometer, das man jede Frage stellen kann, wenn man wei\u00df wie, und in der Lage ist, die Antworten zu verstehen. <strong>Das seltsame und geheime Alethiometer das Lyra besitzt, wird dazu f\u00fchren das sie sich auf eine unglaubliche Reise begibt<\/strong>, die sie in die eisigen arktischen L\u00e4nder f\u00fchren wird, wo die Hexen herrschen und die Eisb\u00e4ren k\u00e4mpfen. Auf ihrer Reise nimmt Lyra an einer Rettungs-Expedition teil, die von den Gyptern ausgef\u00fchrt wird. Im Norden macht Lyra neue Freunde und Verb\u00fcndete, und lernt wie man das Alethiometer benutzt.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"1024\" src=\"https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151644\/Das-Magische-Messer_Philip-Pullman_kevinmaschke.com_-1-700x1024.webp\" alt=\"\" class=\"wp-image-9139\" style=\"width:200px\" srcset=\"https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151644\/Das-Magische-Messer_Philip-Pullman_kevinmaschke.com_-1-700x1024.webp 700w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151644\/Das-Magische-Messer_Philip-Pullman_kevinmaschke.com_-1-274x400.webp 274w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151644\/Das-Magische-Messer_Philip-Pullman_kevinmaschke.com_-1-68x100.webp 68w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151644\/Das-Magische-Messer_Philip-Pullman_kevinmaschke.com_-1-1050x1536.webp 1050w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151644\/Das-Magische-Messer_Philip-Pullman_kevinmaschke.com_-1-100x146.webp 100w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151644\/Das-Magische-Messer_Philip-Pullman_kevinmaschke.com_-1.webp 1094w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Das Magische Messer<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Will muss seine Mutter vor ihren imagin\u00e4ren \u00c4ngsten zu sch\u00fctzen<\/strong>. Doch eines Tages, als zwei mysteri\u00f6se M\u00e4nner erscheinen um Informationen \u00fcber seinen vermissten Vater zu bekommen, entdeckt er dass diese \u00c4ngste mehr als real sind. W\u00e4hrend seiner Flucht findet er ein mysteri\u00f6ses Fenster das ihn in eine andere Welt f\u00fchrt. Dort trifft er die st\u00fcrmische und geheimnisvolle Lyra, ein M\u00e4dchen, das behauptet aus einer dritten Welt zu kommen und ihm verspricht ihm dabei zu helfen seinen Vater zu finden. <strong>In dieser Welt erh\u00e4lt Will einen Dolch mit der besonderen F\u00e4higkeit, Fenster zwischen den verschiedenen Parallelwelten zu \u00f6ffnen<\/strong>. Beide Kinder, mit Hilfe von Verb\u00fcndeten, beginnen eine Reise auf der Suche nach Antworten \u00fcber den Staub und Wills Vater.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"694\" height=\"1024\" src=\"https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151649\/Das-Bernstein-Teleskop_Philip-Pullman_kevinmaschke.com_-1-694x1024.webp\" alt=\"\" class=\"wp-image-9140\" style=\"width:200px\" srcset=\"https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151649\/Das-Bernstein-Teleskop_Philip-Pullman_kevinmaschke.com_-1-694x1024.webp 694w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151649\/Das-Bernstein-Teleskop_Philip-Pullman_kevinmaschke.com_-1-271x400.webp 271w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151649\/Das-Bernstein-Teleskop_Philip-Pullman_kevinmaschke.com_-1-68x100.webp 68w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151649\/Das-Bernstein-Teleskop_Philip-Pullman_kevinmaschke.com_-1-1042x1536.webp 1042w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151649\/Das-Bernstein-Teleskop_Philip-Pullman_kevinmaschke.com_-1-100x147.webp 100w, https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151649\/Das-Bernstein-Teleskop_Philip-Pullman_kevinmaschke.com_-1.webp 1085w\" sizes=\"auto, (max-width: 694px) 100vw, 694px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Das Bernstein-Teleskop<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Will befindet sich in der Gesellschaft von zwei abtr\u00fcnnigen Engeln, die ihn zu Lord Asriel bringen wollen, aber er ignoriert sie, um mit der Hilfe von Chevalier Tialys und Lady Salmakia Lyra zu retten. <strong>Gemeinsam begeben sie sich in die Welt der Toten und reisen&nbsp;in die Welt der Mulefa<\/strong>, wo sie die wahre Natur des Staubs entdecken. W\u00e4hrenddessen findet eine gro\u00dfe Schlacht zwischen der Autorit\u00e4t und der Armee von Lord Asriel stat. Will und Lyra verlieben sich, aber m\u00fcssen das Magische Messer zerst\u00f6ren, und damit die Fenster zwischen den verschiedenen Parallelwelten schlie\u00dfen, und sich verurteilen f\u00fcr immer getrennt zu bleiben.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Meinung<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ich habe den Film <em>Der Goldenen Kompass<\/em>&nbsp;in 2007, kurz nach seiner Ver\u00f6ffentlichung gesehen, und konnte mich kaum noch dran erinnern als ich anfing die Trilogie zu lesen, und die Wahrheit ist, dass ich mich dar\u00fcber nicht beschweren kann, <strong>weil die B\u00fccher mich vom ersten Kapitel bis zum letzen Wort komplett absorbiert haben<\/strong>. Die Geschichte ist einzigartig, und die Charaktere werden von Kapitel zu Kapitel interessanter (einige mehr als andere) und abwechslungsreicher. <strong>Ich h\u00e4tte es gern gehabt das der Schriftsteller in einigen Punkten noch etwas vertieft h\u00e4tte<\/strong> &#8211; wie zum Beispiel bei dem Charakter von Mary Malone, ihrer Geschichte und die Rolle die sie spielt &#8211; <strong>aber es ist ja auch gut einige Dinge der Phantasie zu \u00fcberlassen<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ich freu mich schon auf <em>La Belle Sauvage<\/em><\/strong>, das erste Buch in Philip Pullmans vor kurzem angek\u00fcndigter neuer Trilogie, die<em> The Book of Dust<\/em> gennant ist, und <strong>die laut dem Schriftsteller weder ein Prequel noch Fortsetzung ist<\/strong>, sondern eine zeitgleiche Nebengeschichte, die neue Charaktere einf\u00fchrt und andere schon vertraute Charaktere teilt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ich Pers\u00f6nlich empfehle die <em>His Dark Materials<\/em> Trilogie&nbsp;jedem<\/strong>, der Fantasy-Romane mit einer gro\u00dfartigen Geschichte und sehr interessanten (und vielleicht ungew\u00f6hnlichen) Ideen liebt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Bewertung<\/h3>\n\n\n\t<link href=\"https:\/\/fonts.googleapis.com\/css?family=Open+Sans:400,700\" rel=\"stylesheet\">\n\t<style type=\"text\/css\">\n\t\t.wp-review-4410.review-wrapper { font-family: 'Open Sans', sans-serif; }\n\t<\/style>\n\n<div id=\"review\" class=\"review-wrapper wp-review-4410 wp-review-star-type wp-review-default-template delay-animation\">\n\t\t\t<div class=\"review-heading\">\n\t\t\t<h5 class=\"review-title\">\n\t\t\t\tHis Dark Materials\n\t\t\t\t\t\t\t<\/h5>\n\t\t<\/div>\n\t\n\t\n\t<ul class=\"review-list\">\n\t\t\t<li>\n\t\t\t<span>Geschichte<\/span>\n\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #d6d6d6;\">\n\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#718ed6;\">\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t<\/div><!-- .review-result -->\n\n\t<\/div><!-- .review-result-wrapper -->\n\t\n<\/div><!-- .review-star -->\n\t\t<\/li>\n\t\t\t<li>\n\t\t\t<span>Erz\u00e4hlung<\/span>\n\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #d6d6d6;\">\n\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:80%; color:#718ed6;\">\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t<\/div><!-- .review-result -->\n\n\t<\/div><!-- .review-result-wrapper -->\n\t\n<\/div><!-- .review-star -->\n\t\t<\/li>\n\t\t\t<li>\n\t\t\t<span>Unterhaltung<\/span>\n\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #d6d6d6;\">\n\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:90%; color:#718ed6;\">\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t<\/div><!-- .review-result -->\n\n\t<\/div><!-- .review-result-wrapper -->\n\t\n<\/div><!-- .review-star -->\n\t\t<\/li>\n\t\t\t<li>\n\t\t\t<span>Empfehlenswert<\/span>\n\t\t\t<div class=\"review-star\">\n\t<div class=\"review-result-wrapper\" style=\"color: #d6d6d6;\">\n\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\n\t\t<div class=\"review-result\" style=\"width:100%; color:#718ed6;\">\n\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<i class=\"fa fa-star\"><\/i>\n\t\t\t\t\t\t\t<\/div><!-- .review-result -->\n\n\t<\/div><!-- .review-result-wrapper -->\n\t\n<\/div><!-- .review-star -->\n\t\t<\/li>\n\t<\/ul><!-- End .review-list -->\n\n\t\n\t\n\t\n\t\n\t<\/div>\n\n<style type=\"text\/css\">\n\t.wp-review-4410.review-wrapper {\n\t\twidth: 100%;\n\t\tfloat: left;\n\t}\n\t.wp-review-4410.review-wrapper,\n\t.wp-review-4410 .review-title,\n\t.wp-review-4410 .review-desc p,\n\t.wp-review-4410 .reviewed-item p {\n\t\tcolor: #424242;\n\t}\n\t.wp-review-4410 .review-title {\n\t\tpadding-top: 15px;\n\t\tfont-weight: bold;\n\t}\n\t.wp-review-4410 .review-links a {\n\t\tcolor: #718ed6;\n\t}\n\t.wp-review-4410 .review-links a:hover {\n\t\tbackground: #718ed6;\n\t\tcolor: #fff;\n\t}\n\t.wp-review-4410 .review-list li,\n\t.wp-review-4410.review-wrapper {\n\t\tbackground: #ffffff;\n\t}\n\t.wp-review-4410 .review-title,\n\t.wp-review-4410 .review-list li:nth-child(2n),\n\t.wp-review-4410 .wpr-user-features-rating .user-review-title {\n\t\tbackground: #ffffff;\n\t}\n\t.wp-review-4410.review-wrapper,\n\t.wp-review-4410 .review-title,\n\t.wp-review-4410 .review-list li,\n\t.wp-review-4410 .review-list li:last-child,\n\t.wp-review-4410 .user-review-area,\n\t.wp-review-4410 .reviewed-item,\n\t.wp-review-4410 .review-links,\n\t.wp-review-4410 .wpr-user-features-rating {\n\t\tborder-color: #d1d1d1;\n\t}\n\t.wp-review-4410 .wpr-rating-accept-btn {\n\t\tbackground: #718ed6;\n\t}\n\t.wp-review-4410.review-wrapper .user-review-title {\n\t\tcolor: inherit;\n\t}\n\t.wp-review-4410.review-wrapper .user-review-area .review-circle { height: 32px; }\n<\/style>\n<script type=\"application\/ld+json\">\n{\n    \"@context\": \"http:\/\/schema.org\",\n    \"@type\": \"Book\",\n    \"name\": \"His Dark Materials Trilogie\",\n    \"description\": \"His Dark Materials ist eine Fantasy-Trilogie von Philip Pullman die aus den B\u00fcchern Der Goldene Kompass, Das Magische Messer und Das Bernstein-Teleskop besteht, und in der wir ein Waisenm\u00e4dchen namens Lyra durch mehrere Universen folgen  in denen Magie, Theologie und Wissenschaft auf diskrete und zugleich gro\u00dfartige Weise verflochten sind.\",\n    \"image\": \"https:\/\/cdn.kevinmaschke.com\/wp-content\/uploads\/2025\/12\/07151653\/Der-Goldene-Kompass_Philip-Pullman_kevinmaschke.com_-1.webp\",\n    \"url\": \"http:\/\/www.philip-pullman.com\/hdm\",\n    \"author\": \"Philip Pullman\",\n    \"bookFormat\": \"Paperback\",\n    \"review\": {\n        \"@type\": \"Review\",\n        \"reviewRating\": {\n            \"@type\": \"Rating\",\n            \"ratingValue\": 4.6,\n            \"bestRating\": 5,\n            \"worstRating\": 0\n        },\n        \"author\": {\n            \"@type\": \"Person\",\n            \"name\": \"Kevin Maschke\"\n        },\n        \"reviewBody\": \"\"\n    }\n}\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>Sieht aus also w\u00fcrde ich in letzter zeit nur Trilogien lesen! Und nach den K\u00f6nigs-Romanen, der Trajan Trilogie (nur in Spanisch) und der Weltraum Odyssee, war die His Dark Materials Trilogie an der Reihe. His &#8230;<\/p>\n","protected":false},"author":1,"featured_media":4427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[210],"tags":[1705,1704,1703,1702,1706,1693],"class_list":["post-4410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buecher","tag-das-bernstein-teleskop","tag-das-magische-messer","tag-der-goldene-kompass","tag-his-dark-materials-de","tag-northern-lights-de","tag-phillip-pullman-de"],"acf":{"book_cover":9141,"special_featured_image":null},"_links":{"self":[{"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/posts\/4410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/comments?post=4410"}],"version-history":[{"count":0,"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/posts\/4410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/media\/4427"}],"wp:attachment":[{"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/media?parent=4410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/categories?post=4410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kevinmaschke.com\/de\/wp-json\/wp\/v2\/tags?post=4410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}